{"id":10719,"date":"2024-05-22T16:33:35","date_gmt":"2024-05-22T16:33:35","guid":{"rendered":"https:\/\/amechfilms.com\/?post_type=munio_portfolio&#038;p=10719"},"modified":"2024-08-22T06:43:46","modified_gmt":"2024-08-22T06:43:46","slug":"uala-el-elegido","status":"publish","type":"munio_portfolio","link":"https:\/\/amechfilms.com\/en\/munio_portfolio\/uala-el-elegido\/","title":{"rendered":"Ual\u00e1 &#8211; El elegido"},"content":{"rendered":"<div style=\"height:150px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-munio-gutenberg-title\">EL ELEGIDO<\/h1>\n\n\n\n<p class=\"has-medium-font-size\">CLIENT: UAL\u00c1<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ual\u00e1 - El Elegido\" src=\"https:\/\/player.vimeo.com\/video\/942143292?h=79f09d9da8&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"281\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Directed by: Patricio Oseguera<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Produced by: Ximena Jimenez &amp; Oscar Huerta<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Cinematographer: Bel\u00e9n Garc\u00eda<\/p>\n\n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"template":"","portfolio_category":[12,20,18],"_links":{"self":[{"href":"https:\/\/amechfilms.com\/en\/wp-json\/wp\/v2\/munio_portfolio\/10719"}],"collection":[{"href":"https:\/\/amechfilms.com\/en\/wp-json\/wp\/v2\/munio_portfolio"}],"about":[{"href":"https:\/\/amechfilms.com\/en\/wp-json\/wp\/v2\/types\/munio_portfolio"}],"wp:attachment":[{"href":"https:\/\/amechfilms.com\/en\/wp-json\/wp\/v2\/media?parent=10719"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/amechfilms.com\/en\/wp-json\/wp\/v2\/portfolio_category?post=10719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}